{"id":3,"date":"2023-02-11T14:20:30","date_gmt":"2023-02-11T13:20:30","guid":{"rendered":"https:\/\/patent-viewer.eu\/?page_id=3"},"modified":"2023-12-16T17:19:36","modified_gmt":"2023-12-16T16:19:36","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/patent-viewer.eu\/index.php\/privacy-policy\/","title":{"rendered":"Datenschutzerkl\u00e4rung"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3\" class=\"elementor elementor-3\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d3b2894 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d3b2894\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7156cd1f\" data-id=\"7156cd1f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35a83e60 elementor-widget elementor-widget-text-editor\" data-id=\"35a83e60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><p><!-- [if gte mso 9]><xml><br \/> <o:OfficeDocumentSettings><br \/>  <o:AllowPNG\/><br \/> <\/o:OfficeDocumentSettings><br \/><\/xml><![endif]--><!-- [if gte mso 9]><xml><br \/> <w:WordDocument><br \/>  <w:View>Normal<\/w:View><br \/>  <w:Zoom>0<\/w:Zoom><br \/>  <w:TrackMoves\/><br \/>  <w:TrackFormatting\/><br \/>  <w:PunctuationKerning\/><br \/>  <w:ValidateAgainstSchemas\/><br \/>  <w:SaveIfXMLInvalid>false<\/w:SaveIfXMLInvalid><br \/>  <w:IgnoreMixedContent>false<\/w:IgnoreMixedContent><br \/>  <w:AlwaysShowPlaceholderText>false<\/w:AlwaysShowPlaceholderText><br \/>  <w:DoNotPromoteQF\/><br \/>  <w:LidThemeOther>EN-GB<\/w:LidThemeOther><br \/>  <w:LidThemeAsian>X-NONE<\/w:LidThemeAsian><br \/>  <w:LidThemeComplexScript>X-NONE<\/w:LidThemeComplexScript><br \/>  <w:Compatibility><br \/>   <w:BreakWrappedTables\/><br \/>   <w:SnapToGridInCell\/><br \/>   <w:WrapTextWithPunct\/><br \/>   <w:UseAsianBreakRules\/><br \/>   <w:DontGrowAutofit\/><br \/>   <w:SplitPgBreakAndParaMark\/><br \/>   <w:EnableOpenTypeKerning\/><br \/>   <w:DontFlipMirrorIndents\/><br \/>   <w:OverrideTableStyleHps\/><br \/>  <\/w:Compatibility><br \/>  <m:mathPr><br \/>   <m:mathFont m:val=\"Cambria Math\"\/><br \/>   <m:brkBin m:val=\"before\"\/><br \/>   <m:brkBinSub m:val=\"&#45;-\"\/><br \/>   <m:smallFrac m:val=\"off\"\/><br \/>   <m:dispDef\/><br \/>   <m:lMargin m:val=\"0\"\/><br \/>   <m:rMargin m:val=\"0\"\/><br \/>   <m:defJc m:val=\"centerGroup\"\/><br \/>   <m:wrapIndent m:val=\"1440\"\/><br \/>   <m:intLim m:val=\"subSup\"\/><br \/>   <m:naryLim m:val=\"undOvr\"\/><br \/>  <\/m:mathPr><\/w:WordDocument><br \/><\/xml><![endif]--><!-- [if gte mso 9]><xml><br \/> <w:LatentStyles DefLockedState=\"false\" DefUnhideWhenUsed=\"false\" DefSemiHidden=\"false\" DefQFormat=\"false\" DefPriority=\"99\" LatentStyleCount=\"371\"><br \/>  <w:LsdException Locked=\"false\" Priority=\"0\" QFormat=\"true\" Name=\"Normal\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"9\" QFormat=\"true\" Name=\"heading 1\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"9\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" QFormat=\"true\" Name=\"heading 2\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"9\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" QFormat=\"true\" Name=\"heading 3\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"9\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" QFormat=\"true\" Name=\"heading 4\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"9\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" QFormat=\"true\" Name=\"heading 5\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"9\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" QFormat=\"true\" Name=\"heading 6\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"9\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" QFormat=\"true\" Name=\"heading 7\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"9\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" QFormat=\"true\" Name=\"heading 8\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"9\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" QFormat=\"true\" Name=\"heading 9\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"index 1\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"index 2\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"index 3\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"index 4\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"index 5\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"index 6\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"index 7\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"index 8\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"index 9\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"39\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"toc 1\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"39\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"toc 2\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"39\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"toc 3\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"39\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"toc 4\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"39\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"toc 5\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"39\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"toc 6\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"39\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"toc 7\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"39\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"toc 8\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"39\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"toc 9\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Normal Indent\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"footnote text\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"annotation text\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"header\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"footer\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"index heading\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"35\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" QFormat=\"true\" Name=\"caption\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"table of figures\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"envelope address\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"envelope return\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"footnote reference\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"annotation reference\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"line number\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"page number\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"endnote reference\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"endnote text\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"table of authorities\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"macro\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"toa heading\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Bullet\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Number\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List 2\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List 3\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List 4\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List 5\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Bullet 2\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Bullet 3\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Bullet 4\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Bullet 5\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Number 2\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Number 3\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Number 4\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Number 5\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"10\" QFormat=\"true\" Name=\"Title\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Closing\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Signature\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"1\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Default Paragraph Font\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Body Text\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Body Text Indent\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Continue\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Continue 2\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Continue 3\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Continue 4\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Continue 5\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Message Header\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"11\" QFormat=\"true\" Name=\"Subtitle\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Salutation\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Date\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Body Text First Indent\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Body Text First Indent 2\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Note Heading\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Body Text 2\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Body Text 3\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Body Text Indent 2\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Body Text Indent 3\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Block Text\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Hyperlink\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"FollowedHyperlink\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"22\" QFormat=\"true\" Name=\"Strong\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"20\" QFormat=\"true\" Name=\"Emphasis\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Document Map\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Plain Text\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"E-mail Signature\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"HTML Top of Form\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"HTML Bottom of Form\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Normal (Web)\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"HTML Acronym\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"HTML Address\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"HTML Cite\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"HTML Code\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"HTML Definition\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"HTML Keyboard\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"HTML Preformatted\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"HTML Sample\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"HTML Typewriter\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"HTML Variable\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Normal Table\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"annotation subject\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"No List\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Outline List 1\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Outline List 2\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Outline List 3\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Simple 1\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Simple 2\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Simple 3\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Classic 1\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Classic 2\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Classic 3\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Classic 4\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Colorful 1\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Colorful 2\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Colorful 3\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Columns 1\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Columns 2\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Columns 3\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Columns 4\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Columns 5\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Grid 1\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Grid 2\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Grid 3\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Grid 4\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Grid 5\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Grid 6\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Grid 7\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Grid 8\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table List 1\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table List 2\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table List 3\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table List 4\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table List 5\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table List 6\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table List 7\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table List 8\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table 3D effects 1\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table 3D effects 2\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table 3D effects 3\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Contemporary\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Elegant\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Professional\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Subtle 1\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Subtle 2\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Web 1\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Web 2\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Web 3\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Balloon Text\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"39\" Name=\"Table Grid\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Theme\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" Name=\"Placeholder Text\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"1\" QFormat=\"true\" Name=\"No Spacing\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"60\" Name=\"Light Shading\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"61\" Name=\"Light List\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"62\" Name=\"Light Grid\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"63\" Name=\"Medium Shading 1\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"64\" Name=\"Medium Shading 2\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"65\" Name=\"Medium List 1\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"66\" Name=\"Medium List 2\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"67\" Name=\"Medium Grid 1\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"68\" Name=\"Medium Grid 2\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"69\" Name=\"Medium Grid 3\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"70\" Name=\"Dark List\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"71\" Name=\"Colorful Shading\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"72\" Name=\"Colorful List\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"73\" Name=\"Colorful Grid\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"60\" Name=\"Light Shading Accent 1\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"61\" Name=\"Light List Accent 1\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"62\" Name=\"Light Grid Accent 1\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"63\" Name=\"Medium Shading 1 Accent 1\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"64\" Name=\"Medium Shading 2 Accent 1\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"65\" Name=\"Medium List 1 Accent 1\"\/><br \/>  <w:LsdException Locked=\"false\" SemiHidden=\"true\" Name=\"Revision\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"34\" QFormat=\"true\" Name=\"List Paragraph\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"29\" QFormat=\"true\" Name=\"Quote\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"30\" QFormat=\"true\" Name=\"Intense Quote\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"66\" Name=\"Medium List 2 Accent 1\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"67\" Name=\"Medium Grid 1 Accent 1\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"68\" Name=\"Medium Grid 2 Accent 1\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"69\" Name=\"Medium Grid 3 Accent 1\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"70\" Name=\"Dark List Accent 1\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"71\" Name=\"Colorful Shading Accent 1\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"72\" Name=\"Colorful List Accent 1\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"73\" Name=\"Colorful Grid Accent 1\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"60\" Name=\"Light Shading Accent 2\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"61\" Name=\"Light List Accent 2\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"62\" Name=\"Light Grid Accent 2\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"63\" Name=\"Medium Shading 1 Accent 2\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"64\" Name=\"Medium Shading 2 Accent 2\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"65\" Name=\"Medium List 1 Accent 2\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"66\" Name=\"Medium List 2 Accent 2\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"67\" Name=\"Medium Grid 1 Accent 2\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"68\" Name=\"Medium Grid 2 Accent 2\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"69\" Name=\"Medium Grid 3 Accent 2\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"70\" Name=\"Dark List Accent 2\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"71\" Name=\"Colorful Shading Accent 2\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"72\" Name=\"Colorful List Accent 2\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"73\" Name=\"Colorful Grid Accent 2\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"60\" Name=\"Light Shading Accent 3\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"61\" Name=\"Light List Accent 3\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"62\" Name=\"Light Grid Accent 3\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"63\" Name=\"Medium Shading 1 Accent 3\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"64\" Name=\"Medium Shading 2 Accent 3\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"65\" Name=\"Medium List 1 Accent 3\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"66\" Name=\"Medium List 2 Accent 3\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"67\" Name=\"Medium Grid 1 Accent 3\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"68\" Name=\"Medium Grid 2 Accent 3\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"69\" Name=\"Medium Grid 3 Accent 3\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"70\" Name=\"Dark List Accent 3\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"71\" Name=\"Colorful Shading Accent 3\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"72\" Name=\"Colorful List Accent 3\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"73\" Name=\"Colorful Grid Accent 3\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"60\" Name=\"Light Shading Accent 4\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"61\" Name=\"Light List Accent 4\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"62\" Name=\"Light Grid Accent 4\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"63\" Name=\"Medium Shading 1 Accent 4\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"64\" Name=\"Medium Shading 2 Accent 4\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"65\" Name=\"Medium List 1 Accent 4\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"66\" Name=\"Medium List 2 Accent 4\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"67\" Name=\"Medium Grid 1 Accent 4\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"68\" Name=\"Medium Grid 2 Accent 4\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"69\" Name=\"Medium Grid 3 Accent 4\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"70\" Name=\"Dark List Accent 4\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"71\" Name=\"Colorful Shading Accent 4\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"72\" Name=\"Colorful List Accent 4\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"73\" Name=\"Colorful Grid Accent 4\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"60\" Name=\"Light Shading Accent 5\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"61\" Name=\"Light List Accent 5\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"62\" Name=\"Light Grid Accent 5\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"63\" Name=\"Medium Shading 1 Accent 5\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"64\" Name=\"Medium Shading 2 Accent 5\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"65\" Name=\"Medium List 1 Accent 5\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"66\" Name=\"Medium List 2 Accent 5\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"67\" Name=\"Medium Grid 1 Accent 5\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"68\" Name=\"Medium Grid 2 Accent 5\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"69\" Name=\"Medium Grid 3 Accent 5\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"70\" Name=\"Dark List Accent 5\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"71\" Name=\"Colorful Shading Accent 5\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"72\" Name=\"Colorful List Accent 5\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"73\" Name=\"Colorful Grid Accent 5\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"60\" Name=\"Light Shading Accent 6\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"61\" Name=\"Light List Accent 6\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"62\" Name=\"Light Grid Accent 6\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"63\" Name=\"Medium Shading 1 Accent 6\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"64\" Name=\"Medium Shading 2 Accent 6\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"65\" Name=\"Medium List 1 Accent 6\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"66\" Name=\"Medium List 2 Accent 6\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"67\" Name=\"Medium Grid 1 Accent 6\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"68\" Name=\"Medium Grid 2 Accent 6\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"69\" Name=\"Medium Grid 3 Accent 6\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"70\" Name=\"Dark List Accent 6\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"71\" Name=\"Colorful Shading Accent 6\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"72\" Name=\"Colorful List Accent 6\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"73\" Name=\"Colorful Grid Accent 6\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"19\" QFormat=\"true\" Name=\"Subtle Emphasis\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"21\" QFormat=\"true\" Name=\"Intense Emphasis\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"31\" QFormat=\"true\" Name=\"Subtle Reference\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"32\" QFormat=\"true\" Name=\"Intense Reference\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"33\" QFormat=\"true\" Name=\"Book Title\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"37\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Bibliography\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"39\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" QFormat=\"true\" Name=\"TOC Heading\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"41\" Name=\"Plain Table 1\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"42\" Name=\"Plain Table 2\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"43\" Name=\"Plain Table 3\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"44\" Name=\"Plain Table 4\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"45\" Name=\"Plain Table 5\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"40\" Name=\"Grid Table Light\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"46\" Name=\"Grid Table 1 Light\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"47\" Name=\"Grid Table 2\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"48\" Name=\"Grid Table 3\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"49\" Name=\"Grid Table 4\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"50\" Name=\"Grid Table 5 Dark\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"51\" Name=\"Grid Table 6 Colorful\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"52\" Name=\"Grid Table 7 Colorful\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"46\" Name=\"Grid Table 1 Light Accent 1\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"47\" Name=\"Grid Table 2 Accent 1\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"48\" Name=\"Grid Table 3 Accent 1\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"49\" Name=\"Grid Table 4 Accent 1\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"50\" Name=\"Grid Table 5 Dark Accent 1\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"51\" Name=\"Grid Table 6 Colorful Accent 1\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"52\" Name=\"Grid Table 7 Colorful Accent 1\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"46\" Name=\"Grid Table 1 Light Accent 2\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"47\" Name=\"Grid Table 2 Accent 2\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"48\" Name=\"Grid Table 3 Accent 2\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"49\" Name=\"Grid Table 4 Accent 2\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"50\" Name=\"Grid Table 5 Dark Accent 2\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"51\" Name=\"Grid Table 6 Colorful Accent 2\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"52\" Name=\"Grid Table 7 Colorful Accent 2\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"46\" Name=\"Grid Table 1 Light Accent 3\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"47\" Name=\"Grid Table 2 Accent 3\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"48\" Name=\"Grid Table 3 Accent 3\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"49\" Name=\"Grid Table 4 Accent 3\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"50\" Name=\"Grid Table 5 Dark Accent 3\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"51\" Name=\"Grid Table 6 Colorful Accent 3\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"52\" Name=\"Grid Table 7 Colorful Accent 3\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"46\" Name=\"Grid Table 1 Light Accent 4\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"47\" Name=\"Grid Table 2 Accent 4\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"48\" Name=\"Grid Table 3 Accent 4\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"49\" Name=\"Grid Table 4 Accent 4\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"50\" Name=\"Grid Table 5 Dark Accent 4\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"51\" Name=\"Grid Table 6 Colorful Accent 4\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"52\" Name=\"Grid Table 7 Colorful Accent 4\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"46\" Name=\"Grid Table 1 Light Accent 5\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"47\" Name=\"Grid Table 2 Accent 5\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"48\" Name=\"Grid Table 3 Accent 5\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"49\" Name=\"Grid Table 4 Accent 5\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"50\" Name=\"Grid Table 5 Dark Accent 5\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"51\" Name=\"Grid Table 6 Colorful Accent 5\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"52\" Name=\"Grid Table 7 Colorful Accent 5\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"46\" Name=\"Grid Table 1 Light Accent 6\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"47\" Name=\"Grid Table 2 Accent 6\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"48\" Name=\"Grid Table 3 Accent 6\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"49\" Name=\"Grid Table 4 Accent 6\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"50\" Name=\"Grid Table 5 Dark Accent 6\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"51\" Name=\"Grid Table 6 Colorful Accent 6\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"52\" Name=\"Grid Table 7 Colorful Accent 6\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"46\" Name=\"List Table 1 Light\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"47\" Name=\"List Table 2\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"48\" Name=\"List Table 3\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"49\" Name=\"List Table 4\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"50\" Name=\"List Table 5 Dark\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"51\" Name=\"List Table 6 Colorful\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"52\" Name=\"List Table 7 Colorful\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"46\" Name=\"List Table 1 Light Accent 1\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"47\" Name=\"List Table 2 Accent 1\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"48\" Name=\"List Table 3 Accent 1\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"49\" Name=\"List Table 4 Accent 1\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"50\" Name=\"List Table 5 Dark Accent 1\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"51\" Name=\"List Table 6 Colorful Accent 1\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"52\" Name=\"List Table 7 Colorful Accent 1\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"46\" Name=\"List Table 1 Light Accent 2\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"47\" Name=\"List Table 2 Accent 2\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"48\" Name=\"List Table 3 Accent 2\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"49\" Name=\"List Table 4 Accent 2\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"50\" Name=\"List Table 5 Dark Accent 2\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"51\" Name=\"List Table 6 Colorful Accent 2\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"52\" Name=\"List Table 7 Colorful Accent 2\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"46\" Name=\"List Table 1 Light Accent 3\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"47\" Name=\"List Table 2 Accent 3\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"48\" Name=\"List Table 3 Accent 3\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"49\" Name=\"List Table 4 Accent 3\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"50\" Name=\"List Table 5 Dark Accent 3\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"51\" Name=\"List Table 6 Colorful Accent 3\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"52\" Name=\"List Table 7 Colorful Accent 3\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"46\" Name=\"List Table 1 Light Accent 4\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"47\" Name=\"List Table 2 Accent 4\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"48\" Name=\"List Table 3 Accent 4\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"49\" Name=\"List Table 4 Accent 4\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"50\" Name=\"List Table 5 Dark Accent 4\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"51\" Name=\"List Table 6 Colorful Accent 4\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"52\" Name=\"List Table 7 Colorful Accent 4\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"46\" Name=\"List Table 1 Light Accent 5\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"47\" Name=\"List Table 2 Accent 5\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"48\" Name=\"List Table 3 Accent 5\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"49\" Name=\"List Table 4 Accent 5\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"50\" Name=\"List Table 5 Dark Accent 5\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"51\" Name=\"List Table 6 Colorful Accent 5\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"52\" Name=\"List Table 7 Colorful Accent 5\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"46\" Name=\"List Table 1 Light Accent 6\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"47\" Name=\"List Table 2 Accent 6\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"48\" Name=\"List Table 3 Accent 6\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"49\" Name=\"List Table 4 Accent 6\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"50\" Name=\"List Table 5 Dark Accent 6\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"51\" Name=\"List Table 6 Colorful Accent 6\"\/><br \/>  <w:LsdException Locked=\"false\" Priority=\"52\" Name=\"List Table 7 Colorful Accent 6\"\/><br \/> <\/w:LatentStyles><br \/><\/xml><![endif]--><!-- [if gte mso 10]><\/p>\n<style>\n \/* Style Definitions *\/<br \/> table.MsoNormalTable<br \/>\t{mso-style-name:\"Normale Tabelle\";<br \/>\tmso-tstyle-rowband-size:0;<br \/>\tmso-tstyle-colband-size:0;<br \/>\tmso-style-noshow:yes;<br \/>\tmso-style-priority:99;<br \/>\tmso-style-parent:\"\";<br \/>\tmso-padding-alt:0cm 5.4pt 0cm 5.4pt;<br \/>\tmso-para-margin-top:0cm;<br \/>\tmso-para-margin-right:0cm;<br \/>\tmso-para-margin-bottom:8.0pt;<br \/>\tmso-para-margin-left:0cm;<br \/>\tline-height:107%;<br \/>\tmso-pagination:widow-orphan;<br \/>\tfont-size:11.0pt;<br \/>\tfont-family:\"Calibri\",\"sans-serif\";<br \/>\tmso-ascii-font-family:Calibri;<br \/>\tmso-ascii-theme-font:minor-latin;<br \/>\tmso-hansi-font-family:Calibri;<br \/>\tmso-hansi-theme-font:minor-latin;<br \/>\tmso-bidi-font-family:\"Times New Roman\";<br \/>\tmso-bidi-theme-font:minor-bidi;<br \/>\tmso-fareast-language:EN-US;}<br \/><\/style>\n<p><![endif]--><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Wir freuen uns sehr \u00fcber Ihr Interesse an unserem Unternehmen. Datenschutz hat einen besonders hohen Stellenwert f\u00fcr die Gesch\u00e4ftsleitung der Digital Patent Solutions UG (haftungsbeschr\u00e4nkt). Eine Nutzung der Internetseiten der <\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Digital Patent Solutions UG (haftungsbeschr\u00e4nkt)<\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\"> ist grunds\u00e4tzlich ohne jede Angabe personenbezogener Daten m\u00f6glich. Sofern eine betroffene Person besondere Services unseres Unternehmens \u00fcber unsere Internetseite in Anspruch nehmen m\u00f6chte, k\u00f6nnte jedoch eine Verarbeitung personenbezogener Daten erforderlich werden. Ist die Verarbeitung personenbezogener Daten erforderlich und besteht f\u00fcr eine solche Verarbeitung keine gesetzliche Grundlage, holen wir generell eine Einwilligung der betroffenen Person ein.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Die Verarbeitung personenbezogener Daten, beispielsweise des Namens, der Anschrift, E-Mail-Adresse oder Telefonnummer einer betroffenen Person, erfolgt stets im Einklang mit der Datenschutz-Grundverordnung und in \u00dcbereinstimmung mit den f\u00fcr die <\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Digital Patent Solutions UG (haftungsbeschr\u00e4nkt)<\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\"> geltenden landesspezifischen Datenschutzbestimmungen. Mittels dieser Datenschutzerkl\u00e4rung m\u00f6chte unser Unternehmen die \u00d6ffentlichkeit \u00fcber Art, Umfang und Zweck der von uns erhobenen, genutzten und verarbeiteten personenbezogenen Daten informieren. Ferner werden betroffene Personen mittels dieser Datenschutzerkl\u00e4rung \u00fcber die ihnen zustehenden Rechte aufgekl\u00e4rt.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Die <\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Digital Patent Solutions UG (haftungsbeschr\u00e4nkt)<\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\"> hat als f\u00fcr die Verarbeitung Verantwortlicher zahlreiche technische und organisatorische Ma\u00dfnahmen umgesetzt, um einen m\u00f6glichst l\u00fcckenlosen Schutz der \u00fcber diese Internetseite verarbeiteten personenbezogenen Daten sicherzustellen. Dennoch k\u00f6nnen Internetbasierte Daten\u00fcbertragungen grunds\u00e4tzlich Sicherheitsl\u00fccken aufweisen, sodass ein absoluter Schutz nicht gew\u00e4hrleistet werden kann. Aus diesem Grund steht es jeder betroffenen Person frei, personenbezogene Daten auch auf alternativen Wegen, beispielsweise telefonisch, an uns zu \u00fcbermitteln.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><b>1. Begriffsbestimmungen<\/b><\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Die Datenschutzerkl\u00e4rung der <\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Digital Patent Solutions UG (haftungsbeschr\u00e4nkt)<\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\"> beruht auf den Begrifflichkeiten, die durch den Europ\u00e4ischen Richtlinien- und Verordnungsgeber beim Erlass der Datenschutz-Grundverordnung (DS-GVO) verwendet wurden. Unsere Datenschutzerkl\u00e4rung soll sowohl f\u00fcr die \u00d6ffentlichkeit als auch f\u00fcr unsere Kunden und Gesch\u00e4ftspartner einfach lesbar und verst\u00e4ndlich sein. Um dies zu gew\u00e4hrleisten, m\u00f6chten wir vorab die verwendeten Begrifflichkeiten erl\u00e4utern.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Wir verwenden in dieser Datenschutzerkl\u00e4rung unter anderem die folgenden Begriffe:<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>a)<span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>personenbezogene Daten<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Personenbezogene Daten sind alle Informationen, die sich auf eine identifizierte oder identifizierbare nat\u00fcrliche Person (im Folgenden \u201ebetroffene Person\u201c) beziehen. Als identifizierbar wird eine nat\u00fcrliche Person angesehen, die direkt oder indirekt, insbesondere mittels Zuordnung zu einer Kennung wie einem Namen, zu einer Kennnummer, zu Standortdaten, zu einer Online-Kennung oder zu einem oder mehreren besonderen Merkmalen, die Ausdruck der physischen, physiologischen, genetischen, psychischen, wirtschaftlichen, kulturellen oder sozialen Identit\u00e4t dieser nat\u00fcrlichen Person sind, identifiziert werden kann.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>b)<span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>betroffene Person<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Betroffene Person ist jede identifizierte oder identifizierbare nat\u00fcrliche Person, deren personenbezogene Daten von dem f\u00fcr die Verarbeitung Verantwortlichen verarbeitet werden.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>c)<span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Verarbeitung<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Verarbeitung ist jeder mit oder ohne Hilfe automatisierter Verfahren ausgef\u00fchrte Vorgang oder jede solche Vorgangsreihe im Zusammenhang mit personenbezogenen Daten wie das Erheben, das Erfassen, die Organisation, das Ordnen, die Speicherung, die Anpassung oder Ver\u00e4nderung, das Auslesen, das Abfragen, die Verwendung, die Offenlegung durch \u00dcbermittlung, Verbreitung oder eine andere Form der Bereitstellung, den Abgleich oder die Verkn\u00fcpfung, die Einschr\u00e4nkung, das L\u00f6schen oder die Vernichtung.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>d)<span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Einschr\u00e4nkung der Verarbeitung<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Einschr\u00e4nkung der Verarbeitung ist die Markierung gespeicherter personenbezogener Daten mit dem Ziel, ihre k\u00fcnftige Verarbeitung einzuschr\u00e4nken.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>e)<span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Profiling<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Profiling ist jede Art der automatisierten Verarbeitung personenbezogener Daten, die darin besteht, dass diese personenbezogenen Daten verwendet werden, um bestimmte pers\u00f6nliche Aspekte, die sich auf eine nat\u00fcrliche Person beziehen, zu bewerten, insbesondere, um Aspekte bez\u00fcglich Arbeitsleistung, wirtschaftlicher Lage, Gesundheit, pers\u00f6nlicher Vorlieben, Interessen, Zuverl\u00e4ssigkeit, Verhalten, Aufenthaltsort oder Ortswechsel dieser nat\u00fcrlichen Person zu analysieren oder vorherzusagen.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>f)<span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0\u00a0 <\/span>Pseudonymisierung<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Pseudonymisierung ist die Verarbeitung personenbezogener Daten in einer Weise, auf welche die personenbezogenen Daten ohne Hinzuziehung zus\u00e4tzlicher Informationen nicht mehr einer spezifischen betroffenen Person zugeordnet werden k\u00f6nnen, sofern diese zus\u00e4tzlichen Informationen gesondert aufbewahrt werden und technischen und organisatorischen Ma\u00dfnahmen unterliegen, die gew\u00e4hrleisten, dass die personenbezogenen Daten nicht einer identifizierten oder identifizierbaren nat\u00fcrlichen Person zugewiesen werden.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>g)<span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Verantwortlicher oder f\u00fcr die Verarbeitung Verantwortlicher<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Verantwortlicher oder f\u00fcr die Verarbeitung Verantwortlicher ist die nat\u00fcrliche oder juristische Person, Beh\u00f6rde, Einrichtung oder andere Stelle, die allein oder gemeinsam mit anderen \u00fcber die Zwecke und Mittel der Verarbeitung von personenbezogenen Daten entscheidet. Sind die Zwecke und Mittel dieser Verarbeitung durch das Unionsrecht oder das Recht der Mitgliedstaaten vorgegeben, so kann der Verantwortliche beziehungsweise k\u00f6nnen die bestimmten Kriterien seiner Benennung nach dem Unionsrecht oder dem Recht der Mitgliedstaaten vorgesehen werden.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>h)<span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Auftragsverarbeiter<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Auftragsverarbeiter ist eine nat\u00fcrliche oder juristische Person, Beh\u00f6rde, Einrichtung oder andere Stelle, die personenbezogene Daten im Auftrag des Verantwortlichen verarbeitet.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>i)<span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0\u00a0\u00a0 <\/span>Empf\u00e4nger<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Empf\u00e4nger ist eine nat\u00fcrliche oder juristische Person, Beh\u00f6rde, Einrichtung oder andere Stelle, der personenbezogene Daten offengelegt werden, unabh\u00e4ngig davon, ob es sich bei ihr um einen Dritten handelt oder nicht. Beh\u00f6rden, die im Rahmen eines bestimmten Untersuchungsauftrags nach dem Unionsrecht oder dem Recht der Mitgliedstaaten m\u00f6glicherweise personenbezogene Daten erhalten, gelten jedoch nicht als Empf\u00e4nger.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>j)<span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0\u00a0\u00a0 <\/span>Dritter<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Dritter ist eine nat\u00fcrliche oder juristische Person, Beh\u00f6rde, Einrichtung oder andere Stelle au\u00dfer der betroffenen Person, dem Verantwortlichen, dem Auftragsverarbeiter und den Personen, die unter der unmittelbaren Verantwortung des Verantwortlichen oder des Auftragsverarbeiters befugt sind, die personenbezogenen Daten zu verarbeiten.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>k)<span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Einwilligung<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Einwilligung ist jede von der betroffenen Person freiwillig f\u00fcr den bestimmten Fall in informierter Weise und unmissverst\u00e4ndlich abgegebene Willensbekundung in Form einer Erkl\u00e4rung oder einer sonstigen eindeutigen best\u00e4tigenden Handlung, mit der die betroffene Person zu verstehen gibt, dass sie mit der Verarbeitung der sie betreffenden personenbezogenen Daten einverstanden ist.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><b><span lang=\"DE\" style=\"mso-ansi-language: DE;\">2. Name und Anschrift des f\u00fcr die Verarbeitung Verantwortlichen<\/span><\/b><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Verantwortlicher im Sinne der Datenschutz-Grundverordnung, sonstiger in den Mitgliedstaaten der Europ\u00e4ischen Union geltenden Datenschutzgesetze und anderer Bestimmungen mit datenschutzrechtlichem Charakter ist die:<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Digital Patent Solutions UG (haftungsbeschr\u00e4nkt)<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">St.-Michael-Str. 26 <\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">57072 Siegen<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Deutschland<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">E-Mail: info@patent-viewer.eu<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Website: <a href=\"https:\/\/patent-viewer.eu\">www.patent-viewer.eu<\/a><\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><b><span lang=\"DE\" style=\"mso-ansi-language: DE;\">3. Erfassung von allgemeinen Daten und Informationen<\/span><\/b><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Die Internetseite der <\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Digital Patent Solutions UG (haftungsbeschr\u00e4nkt)<\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\"> erfasst mit jedem Aufruf der Internetseite durch eine betroffene Person oder ein automatisiertes System eine Reihe von allgemeinen Daten und Informationen. Diese allgemeinen Daten und Informationen werden in den Logfiles des Servers gespeichert. Erfasst werden k\u00f6nnen die (1) verwendeten Browsertypen und Versionen, (2) das vom zugreifenden System verwendete Betriebssystem, (3) die Internetseite, von welcher ein zugreifendes System auf unsere Internetseite gelangt (sogenannte Referrer), (4) die Unterwebseiten, welche \u00fcber ein zugreifendes System auf unserer Internetseite angesteuert werden, (5) das Datum und die Uhrzeit eines Zugriffs auf die Internetseite, (6) eine Internet-Protokoll-Adresse (IP-Adresse), (7) der Internet-Service-Provider des zugreifenden Systems und (8) sonstige \u00e4hnliche Daten und Informationen, die der Gefahrenabwehr im Falle von Angriffen auf unsere informationstechnologischen Systeme dienen.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Bei der Nutzung dieser allgemeinen Daten und Informationen zieht die <\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Digital Patent Solutions UG (haftungsbeschr\u00e4nkt)<\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\"> keine R\u00fcckschl\u00fcsse auf die betroffene Person. Diese Informationen werden vielmehr ben\u00f6tigt, um (1) die Inhalte unserer Internetseite korrekt auszuliefern, (2) die Inhalte unserer Internetseite sowie die Werbung f\u00fcr diese zu optimieren, (3) die dauerhafte Funktionsf\u00e4higkeit unserer informationstechnologischen Systeme und der Technik unserer Internetseite zu gew\u00e4hrleisten sowie (4) um Strafverfolgungsbeh\u00f6rden im Falle eines Cyberangriffes die zur Strafverfolgung notwendigen Informationen bereitzustellen. Diese anonym erhobenen Daten und Informationen werden durch die <\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Digital Patent Solutions UG (haftungsbeschr\u00e4nkt)<\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\"> daher einerseits statistisch und ferner mit dem Ziel ausgewertet, den Datenschutz und die Datensicherheit in unserem Unternehmen zu erh\u00f6hen, um letztlich ein optimales Schutzniveau f\u00fcr die von uns verarbeiteten personenbezogenen Daten sicherzustellen. Die anonymen Daten der Server-Logfiles werden getrennt von allen durch eine betroffene Person angegebenen personenbezogenen Daten gespeichert.<\/span><\/p><p><b><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/b><\/p><p><b><span lang=\"DE\" style=\"mso-ansi-language: DE;\">4. Routinem\u00e4\u00dfige L\u00f6schung und Sperrung von personenbezogenen Daten<\/span><\/b><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Der f\u00fcr die Verarbeitung Verantwortliche verarbeitet und speichert personenbezogene Daten der betroffenen Person nur f\u00fcr den Zeitraum, der zur Erreichung des Speicherungszwecks erforderlich ist oder sofern dies durch den Europ\u00e4ischen Richtlinien- und Verordnungsgeber oder einen anderen Gesetzgeber in Gesetzen oder Vorschriften, welchen der f\u00fcr die Verarbeitung Verantwortliche unterliegt, vorgesehen wurde.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Entf\u00e4llt der Speicherungszweck oder l\u00e4uft eine vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber oder einem anderen zust\u00e4ndigen Gesetzgeber vorgeschriebene Speicherfrist ab, werden die personenbezogenen Daten routinem\u00e4\u00dfig und entsprechend den gesetzlichen Vorschriften gesperrt oder gel\u00f6scht.<\/span><\/p><p><b><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/b><\/p><p><b><span lang=\"DE\" style=\"mso-ansi-language: DE;\">5. Rechte der betroffenen Person<\/span><\/b><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>a)<span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Recht auf Best\u00e4tigung<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Jede betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber einger\u00e4umte Recht, von dem f\u00fcr die Verarbeitung Verantwortlichen eine Best\u00e4tigung dar\u00fcber zu verlangen, ob sie betreffende personenbezogene Daten verarbeitet werden. M\u00f6chte eine betroffene Person dieses Best\u00e4tigungsrecht in Anspruch nehmen, kann sie sich hierzu jederzeit an einen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>b)<span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Recht auf Auskunft<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, jederzeit von dem f\u00fcr die Verarbeitung Verantwortlichen unentgeltliche Auskunft \u00fcber die zu seiner Person gespeicherten personenbezogenen Daten und eine Kopie dieser Auskunft zu erhalten. Ferner hat der Europ\u00e4ische Richtlinien- und Verordnungsgeber der betroffenen Person Auskunft \u00fcber folgende Informationen zugestanden:<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><ul><li><span lang=\"DE\" style=\"mso-ansi-language: DE;\">die Verarbeitungszwecke<\/span><\/li><li><span lang=\"DE\" style=\"mso-ansi-language: DE;\">die Kategorien personenbezogener Daten, die verarbeitet werden<\/span><\/li><li><span lang=\"DE\" style=\"mso-ansi-language: DE;\">die Empf\u00e4nger oder Kategorien von Empf\u00e4ngern, gegen\u00fcber denen die personenbezogenen Daten offengelegt worden\u00a0\u00a0\u00a0\u00a0 sind oder noch offengelegt werden, insbesondere bei Empf\u00e4ngern in Drittl\u00e4ndern oder bei internationalen Organisationen<\/span><\/li><li><span lang=\"DE\" style=\"mso-ansi-language: DE;\">falls m\u00f6glich die geplante Dauer, f\u00fcr die die personenbezogenen Daten gespeichert werden, oder, falls dies nicht m\u00f6glich ist, die Kriterien f\u00fcr die Festlegung dieser Dauer<\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\"> <br \/><\/span><\/li><li><span lang=\"DE\" style=\"mso-ansi-language: DE;\">das Bestehen eines Rechts auf Berichtigung oder L\u00f6schung der sie betreffenden personenbezogenen Daten oder auf Einschr\u00e4nkung der Verarbeitung durch den Verantwortlichen oder eines Widerspruchsrechts gegen diese Verarbeitung<\/span><\/li><li><span lang=\"DE\" style=\"mso-ansi-language: DE;\">das Bestehen eines Beschwerderechts bei einer Aufsichtsbeh\u00f6rde<\/span><\/li><li><span lang=\"DE\" style=\"mso-ansi-language: DE;\">wenn die personenbezogenen Daten nicht bei der betroffenen Person erhoben werden: Alle verf\u00fcgbaren Informationen \u00fcber die Herkunft der Daten<\/span><\/li><li><span lang=\"DE\" style=\"mso-ansi-language: DE;\">das Bestehen einer automatisierten Entscheidungsfindung einschlie\u00dflich Profiling gem\u00e4\u00df Artikel 22 Abs.1 und 4 DS-GVO und \u2014 zumindest in diesen F\u00e4llen \u2014 aussagekr\u00e4ftige Informationen \u00fcber die involvierte Logik sowie die Tragweite und die angestrebten Auswirkungen einer derartigen Verarbeitung f\u00fcr die betroffene Person<\/span><\/li><\/ul><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Ferner steht der betroffenen Person ein Auskunftsrecht dar\u00fcber zu, ob personenbezogene Daten an ein Drittland oder an eine internationale Organisation \u00fcbermittelt wurden. Sofern dies der Fall ist, so steht der betroffenen Person im \u00dcbrigen das Recht zu, Auskunft \u00fcber die geeigneten Garantien im Zusammenhang mit der \u00dcbermittlung zu erhalten.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>M\u00f6chte eine betroffene Person dieses Auskunftsrecht in Anspruch nehmen, kann sie sich hierzu jederzeit an einen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>c)<span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Recht auf Berichtigung<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, die unverz\u00fcgliche Berichtigung sie betreffender unrichtiger personenbezogener Daten zu verlangen. Ferner steht der betroffenen Person das Recht zu, unter Ber\u00fccksichtigung der Zwecke der Verarbeitung, die Vervollst\u00e4ndigung unvollst\u00e4ndiger personenbezogener Daten \u2014 auch mittels einer erg\u00e4nzenden Erkl\u00e4rung \u2014 zu verlangen.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>M\u00f6chte eine betroffene Person dieses Berichtigungsrecht in Anspruch nehmen, kann sie sich hierzu jederzeit an einen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>d)<span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Recht auf L\u00f6schung (Recht auf Vergessen werden)<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, von dem Verantwortlichen zu verlangen, dass die sie betreffenden personenbezogenen Daten unverz\u00fcglich gel\u00f6scht werden, sofern einer der folgenden Gr\u00fcnde zutrifft und soweit die Verarbeitung nicht erforderlich ist:<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><ul><li><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Die personenbezogenen Daten wurden f\u00fcr solche Zwecke erhoben oder auf sonstige Weise verarbeitet, f\u00fcr welche sie nicht mehr notwendig sind.<\/span><\/li><li><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Die betroffene Person widerruft ihre Einwilligung, auf die sich die Verarbeitung gem\u00e4\u00df Art. 6 Abs. 1 Buchstabe a DS-GVO oder Art. 9 Abs. 2 Buchstabe a DS-GVO st\u00fctzte, und es fehlt an einer anderweitigen Rechtsgrundlage f\u00fcr die Verarbeitung.<\/span><\/li><li><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Die betroffene Person legt gem\u00e4\u00df Art. 21 Abs. 1 DS-GVO Widerspruch gegen die Verarbeitung ein, und es liegen keine vorrangigen berechtigten Gr\u00fcnde f\u00fcr die Verarbeitung vor, oder die betroffene Person legt gem\u00e4\u00df Art. 21 Abs. 2 DS-GVO Widerspruch gegen die Verarbeitung ein.<\/span><\/li><li><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Die personenbezogenen Daten wurden unrechtm\u00e4\u00dfig verarbeitet.<\/span><\/li><li><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Die L\u00f6schung der personenbezogenen Daten ist zur Erf\u00fcllung einer rechtlichen Verpflichtung nach dem Unionsrecht oder dem Recht der Mitgliedstaaten erforderlich, dem der Verantwortliche unterliegt.<\/span><\/li><li><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Die personenbezogenen Daten wurden in Bezug auf angebotene Dienste der Informationsgesellschaft gem\u00e4\u00df Art. 8 Abs. 1 DS-GVO erhoben.<\/span><\/li><\/ul><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Sofern einer der oben genannten Gr\u00fcnde zutrifft und eine betroffene Person die L\u00f6schung von personenbezogenen Daten, die bei der <\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Digital Patent Solutions UG (haftungsbeschr\u00e4nkt)<\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0gespeichert sind, veranlassen m\u00f6chte, kann sie sich hierzu jederzeit an einen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden. Der Mitarbeiter der <\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Digital Patent Solutions UG (haftungsbeschr\u00e4nkt)<\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0wird veranlassen, dass dem L\u00f6schverlangen unverz\u00fcglich nachgekommen wird.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0<\/span><span style=\"mso-spacerun: yes;\">\u00a0\u00a0 <\/span>Wurden die personenbezogenen Daten von der <\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Digital Patent Solutions UG (haftungsbeschr\u00e4nkt)<\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\"> \u00f6ffentlich gemacht und ist unser Unternehmen als Verantwortlicher gem\u00e4\u00df Art. 17 Abs. 1 DS-GVO zur L\u00f6schung der personenbezogenen Daten verpflichtet, so trifft die <\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Digital Patent Solutions UG (haftungsbeschr\u00e4nkt)<\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\"> unter Ber\u00fccksichtigung der verf\u00fcgbaren Technologie und der Implementierungskosten angemessene Ma\u00dfnahmen, auch technischer Art, um andere f\u00fcr die Datenverarbeitung Verantwortliche, welche die ver\u00f6ffentlichten personenbezogenen Daten verarbeiten, dar\u00fcber in Kenntnis zu setzen, dass die betroffene Person von diesen anderen f\u00fcr die Datenverarbeitung Verantwortlichen die L\u00f6schung s\u00e4mtlicher Links zu diesen personenbezogenen Daten oder von Kopien oder Replikationen dieser personenbezogenen Daten verlangt hat, soweit die Verarbeitung nicht erforderlich ist. Der Mitarbeiter der <\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Digital Patent Solutions UG (haftungsbeschr\u00e4nkt)<\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\"> wird im Einzelfall das Notwendige veranlassen.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>e)<span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Recht auf Einschr\u00e4nkung der Verarbeitung<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, von dem Verantwortlichen die Einschr\u00e4nkung der Verarbeitung zu verlangen, wenn eine der folgenden Voraussetzungen gegeben ist:<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><ul><li><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Die Richtigkeit der personenbezogenen Daten wird von der betroffenen Person bestritten, und zwar f\u00fcr eine Dauer, die es dem Verantwortlichen erm\u00f6glicht, die Richtigkeit der personenbezogenen Daten zu \u00fcberpr\u00fcfen.<\/span><\/li><li><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Die Verarbeitung ist unrechtm\u00e4\u00dfig, die betroffene Person lehnt die L\u00f6schung der personenbezogenen Daten ab und verlangt stattdessen die Einschr\u00e4nkung der Nutzung der personenbezogenen Daten.<\/span><\/li><li><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Der Verantwortliche ben\u00f6tigt die personenbezogenen Daten f\u00fcr die Zwecke der Verarbeitung nicht l\u00e4nger, die betroffene Person ben\u00f6tigt sie jedoch zur Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen.<\/span><\/li><li><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Die betroffene Person hat Widerspruch gegen die Verarbeitung gem. Art. 21 Abs. 1 DS-GVO eingelegt und es steht noch nicht fest, ob die berechtigten Gr\u00fcnde des Verantwortlichen gegen\u00fcber denen der betroffenen Person \u00fcberwiegen.<\/span><\/li><\/ul><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Sofern eine der oben genannten Voraussetzungen gegeben ist und eine betroffene Person die Einschr\u00e4nkung von personenbezogenen Daten, die bei der <\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Digital Patent Solutions UG (haftungsbeschr\u00e4nkt)<\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\"> gespeichert sind, verlangen m\u00f6chte, kann sie sich hierzu jederzeit an einen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden. Der Mitarbeiter der <\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Digital Patent Solutions UG (haftungsbeschr\u00e4nkt)<\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\"> wird die Einschr\u00e4nkung der Verarbeitung veranlassen.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>f)<span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0\u00a0 <\/span>Recht auf Daten\u00fcbertragbarkeit<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, die sie betreffenden personenbezogenen Daten, welche durch die betroffene Person einem Verantwortlichen bereitgestellt wurden, in einem strukturierten, g\u00e4ngigen und maschinenlesbaren Format zu erhalten. Sie hat au\u00dferdem das Recht, diese Daten einem anderen Verantwortlichen ohne Behinderung durch den Verantwortlichen, dem die personenbezogenen Daten bereitgestellt wurden, zu \u00fcbermitteln, sofern die Verarbeitung auf der Einwilligung gem\u00e4\u00df Art. 6 Abs. 1 Buchstabe a DS-GVO oder Art. 9 Abs. 2 Buchstabe a DS-GVO oder auf einem Vertrag gem\u00e4\u00df Art. 6 Abs. 1 Buchstabe b DS-GVO beruht und die Verarbeitung mithilfe automatisierter Verfahren erfolgt, sofern die Verarbeitung nicht f\u00fcr die Wahrnehmung einer Aufgabe erforderlich ist, die im \u00f6ffentlichen Interesse liegt oder in Aus\u00fcbung \u00f6ffentlicher Gewalt erfolgt, welche dem Verantwortlichen \u00fcbertragen wurde.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Ferner hat die betroffene Person bei der Aus\u00fcbung ihres Rechts auf Daten\u00fcbertragbarkeit gem\u00e4\u00df Art. 20 Abs. 1 DS-GVO das Recht, zu erwirken, dass die personenbezogenen Daten direkt von einem Verantwortlichen an einen anderen Verantwortlichen \u00fcbermittelt werden, soweit dies technisch machbar ist und sofern hiervon nicht die Rechte und Freiheiten anderer Personen beeintr\u00e4chtigt werden.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Zur Geltendmachung des Rechts auf Daten\u00fcbertragbarkeit kann sich die betroffene Person jederzeit an einen Mitarbeiter der <\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Digital Patent Solutions UG (haftungsbeschr\u00e4nkt)<\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\"> wenden.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>g)<span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Recht auf Widerspruch<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, aus Gr\u00fcnden, die sich aus ihrer besonderen Situation ergeben, jederzeit gegen die Verarbeitung sie betreffender personenbezogener Daten, die aufgrund von Art. 6 Abs. 1 Buchstaben e oder f DS-GVO erfolgt, Widerspruch einzulegen. Dies gilt auch f\u00fcr ein auf diese Bestimmungen gest\u00fctztes Profiling.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Die <\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Digital Patent Solutions UG (haftungsbeschr\u00e4nkt)<\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\"> verarbeitet die personenbezogenen Daten im Falle des Widerspruchs nicht mehr, es sei denn, wir k\u00f6nnen zwingende schutzw\u00fcrdige Gr\u00fcnde f\u00fcr die Verarbeitung nachweisen, die den Interessen, Rechten und Freiheiten der betroffenen Person \u00fcberwiegen, oder die Verarbeitung dient der Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Verarbeitet die <\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Digital Patent Solutions UG (haftungsbeschr\u00e4nkt)<\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\"> personenbezogene Daten, um Direktwerbung zu betreiben, so hat die betroffene Person das Recht, jederzeit Widerspruch gegen die Verarbeitung der personenbezogenen Daten zum Zwecke derartiger Werbung einzulegen. Dies gilt auch f\u00fcr das Profiling, soweit es mit solcher Direktwerbung in Verbindung steht. Widerspricht die betroffene Person gegen\u00fcber der <\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Digital Patent Solutions UG (haftungsbeschr\u00e4nkt)<\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\"> der Verarbeitung f\u00fcr Zwecke der Direktwerbung, so wird die <\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Digital Patent Solutions UG (haftungsbeschr\u00e4nkt)<\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\"> die personenbezogenen Daten nicht mehr f\u00fcr diese Zwecke verarbeiten.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Zudem hat die betroffene Person das Recht, aus Gr\u00fcnden, die sich aus ihrer besonderen Situation ergeben, gegen die sie betreffende Verarbeitung personenbezogener Daten, die bei der <\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Digital Patent Solutions UG (haftungsbeschr\u00e4nkt)<\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\"> zu wissenschaftlichen oder historischen Forschungszwecken oder zu statistischen Zwecken gem\u00e4\u00df Art. 89 Abs. 1 DS-GVO erfolgen, Widerspruch einzulegen, es sei denn, eine solche Verarbeitung ist zur Erf\u00fcllung einer im \u00f6ffentlichen Interesse liegenden Aufgabe erforderlich.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Zur Aus\u00fcbung des Rechts auf Widerspruch kann sich die betroffene Person direkt an jeden Mitarbeiter der <\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Digital Patent Solutions UG (haftungsbeschr\u00e4nkt)<\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\"> oder einen anderen Mitarbeiter wenden. Der betroffenen Person steht es ferner frei, im Zusammenhang mit der Nutzung von Diensten der Informationsgesellschaft, ungeachtet der Richtlinie 2002\/58\/EG, ihr Widerspruchsrecht mittels automatisierter Verfahren auszu\u00fcben, bei denen technische Spezifikationen verwendet werden.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>h)<span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Automatisierte Entscheidungen im Einzelfall einschlie\u00dflich Profiling<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, nicht einer ausschlie\u00dflich auf einer automatisierten Verarbeitung \u2014 einschlie\u00dflich Profiling \u2014 beruhenden Entscheidung unterworfen zu werden, die ihr gegen\u00fcber rechtliche Wirkung entfaltet oder sie in \u00e4hnlicher Weise erheblich beeintr\u00e4chtigt, sofern die Entscheidung (1) nicht f\u00fcr den Abschluss oder die Erf\u00fcllung eines Vertrags zwischen der betroffenen Person und dem Verantwortlichen erforderlich ist, oder (2) aufgrund von Rechtsvorschriften der Union oder der Mitgliedstaaten, denen der Verantwortliche unterliegt, zul\u00e4ssig ist und diese Rechtsvorschriften angemessene Ma\u00dfnahmen zur Wahrung der Rechte und Freiheiten sowie der berechtigten Interessen der betroffenen Person enthalten oder (3) mit ausdr\u00fccklicher Einwilligung der betroffenen Person erfolgt.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Ist die Entscheidung (1) f\u00fcr den Abschluss oder die Erf\u00fcllung eines Vertrags zwischen der betroffenen Person und dem Verantwortlichen erforderlich oder (2) erfolgt sie mit ausdr\u00fccklicher Einwilligung der betroffenen Person, trifft die <\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Digital Patent Solutions UG (haftungsbeschr\u00e4nkt)<\/span><span lang=\"DE\" style=\"mso-ansi-language: DE;\"> angemessene Ma\u00dfnahmen, um die Rechte und Freiheiten sowie die berechtigten Interessen der betroffenen Person zu wahren, wozu mindestens das Recht auf Erwirkung des Eingreifens einer Person seitens des Verantwortlichen, auf Darlegung des eigenen Standpunkts und auf Anfechtung der Entscheidung geh\u00f6rt.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>M\u00f6chte die betroffene Person Rechte mit Bezug auf automatisierte Entscheidungen geltend machen, kann sie sich hierzu jederzeit an einen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>i) Recht auf Widerruf einer datenschutzrechtlichen Einwilligung<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, eine Einwilligung zur Verarbeitung personenbezogener Daten jederzeit zu widerrufen.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\"><span style=\"mso-spacerun: yes;\">\u00a0\u00a0\u00a0 <\/span>M\u00f6chte die betroffene Person ihr Recht auf Widerruf einer Einwilligung geltend machen, kann sie sich hierzu jederzeit an einen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><b><span lang=\"DE\" style=\"mso-ansi-language: DE;\">6. Rechtsgrundlage der Verarbeitung<\/span><\/b><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Art. 6 I lit. a DS-GVO dient unserem Unternehmen als Rechtsgrundlage f\u00fcr Verarbeitungsvorg\u00e4nge, bei denen wir eine Einwilligung f\u00fcr einen bestimmten Verarbeitungszweck einholen. Ist die Verarbeitung personenbezogener Daten zur Erf\u00fcllung eines Vertrags, dessen Vertragspartei die betroffene Person ist, erforderlich, wie dies beispielsweise bei Verarbeitungsvorg\u00e4ngen der Fall ist, die f\u00fcr eine Lieferung von Waren oder die Erbringung einer sonstigen Leistung oder Gegenleistung notwendig sind, so beruht die Verarbeitung auf Art. 6 I lit. b DS-GVO. Gleiches gilt f\u00fcr solche Verarbeitungsvorg\u00e4nge die zur Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen erforderlich sind, etwa in F\u00e4llen von Anfragen zur unseren Produkten oder Leistungen. Unterliegt unser Unternehmen einer rechtlichen Verpflichtung durch welche eine Verarbeitung von personenbezogenen Daten erforderlich wird, wie beispielsweise zur Erf\u00fcllung steuerlicher Pflichten, so basiert die Verarbeitung auf Art. 6 I lit. c DS-GVO. In seltenen F\u00e4llen k\u00f6nnte die Verarbeitung von personenbezogenen Daten erforderlich werden, um lebenswichtige Interessen der betroffenen Person oder einer anderen nat\u00fcrlichen Person zu sch\u00fctzen. Dies w\u00e4re beispielsweise der Fall, wenn ein Besucher in unserem Betrieb verletzt werden w\u00fcrde und daraufhin sein Name, sein Alter, seine Krankenkassendaten oder sonstige lebenswichtige Informationen an einen Arzt, ein Krankenhaus oder sonstige Dritte weitergegeben werden m\u00fcssten. Dann w\u00fcrde die Verarbeitung auf Art. 6 I lit. d DS-GVO beruhen. Letztlich k\u00f6nnten Verarbeitungsvorg\u00e4nge auf Art. 6 I lit. f DS-GVO beruhen. Auf dieser Rechtsgrundlage basieren Verarbeitungsvorg\u00e4nge, die von keiner der vorgenannten Rechtsgrundlagen erfasst werden, wenn die Verarbeitung zur Wahrung eines berechtigten Interesses unseres Unternehmens oder eines Dritten erforderlich ist, sofern die Interessen, Grundrechte und Grundfreiheiten des Betroffenen nicht \u00fcberwiegen. Solche Verarbeitungsvorg\u00e4nge sind uns insbesondere deshalb gestattet, weil sie durch den Europ\u00e4ischen Gesetzgeber besonders erw\u00e4hnt wurden. Er vertrat insoweit die Auffassung, dass ein berechtigtes Interesse anzunehmen sein k\u00f6nnte, wenn die betroffene Person ein Kunde des Verantwortlichen ist (Erw\u00e4gungsgrund 47 Satz 2 DS-GVO).<\/span><\/p><p><b><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/b><\/p><p><b><span lang=\"DE\" style=\"mso-ansi-language: DE;\">7. Berechtigte Interessen an der Verarbeitung, die von dem Verantwortlichen oder einem Dritten verfolgt werden<\/span><\/b><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Basiert die Verarbeitung personenbezogener Daten auf Artikel 6 I lit. f DS-GVO ist unser berechtigtes Interesse die Durchf\u00fchrung unserer Gesch\u00e4ftst\u00e4tigkeit zugunsten des Wohlergehens all unserer Mitarbeiter und unserer Anteilseigner.<\/span><\/p><p><b><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/b><\/p><p><b><span lang=\"DE\" style=\"mso-ansi-language: DE;\">8. Dauer, f\u00fcr die die personenbezogenen Daten gespeichert werden<\/span><\/b><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Das Kriterium f\u00fcr die Dauer der Speicherung von personenbezogenen Daten ist die jeweilige gesetzliche Aufbewahrungsfrist. Nach Ablauf der Frist werden die entsprechenden Daten routinem\u00e4\u00dfig gel\u00f6scht, sofern sie nicht mehr zur Vertragserf\u00fcllung oder Vertragsanbahnung erforderlich sind.<\/span><\/p><p><b><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/b><\/p><p><b><span lang=\"DE\" style=\"mso-ansi-language: DE;\">9. Gesetzliche oder vertragliche Vorschriften zur Bereitstellung der personenbezogenen Daten; Erforderlichkeit f\u00fcr den Vertragsabschluss; Verpflichtung der betroffenen Person, die personenbezogenen Daten bereitzustellen; m\u00f6gliche Folgen der Nichtbereitstellung<\/span><\/b><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Wir kl\u00e4ren Sie dar\u00fcber auf, dass die Bereitstellung personenbezogener Daten zum Teil gesetzlich vorgeschrieben ist (z.B. Steuervorschriften) oder sich auch aus vertraglichen Regelungen (z.B. Angaben zum Vertragspartner) ergeben kann. Mitunter kann es zu einem Vertragsschluss erforderlich sein, dass eine betroffene Person uns personenbezogene Daten zur Verf\u00fcgung stellt, die in der Folge durch uns verarbeitet werden m\u00fcssen. Die betroffene Person ist beispielsweise verpflichtet uns personenbezogene Daten bereitzustellen, wenn unser Unternehmen mit ihr einen Vertrag abschlie\u00dft. Eine Nichtbereitstellung der personenbezogenen Daten h\u00e4tte zur Folge, dass der Vertrag mit dem Betroffenen nicht geschlossen werden k\u00f6nnte. Vor einer Bereitstellung personenbezogener Daten durch den Betroffenen muss sich der Betroffene an einen unserer Mitarbeiter wenden. Unser Mitarbeiter kl\u00e4rt den Betroffenen einzelfallbezogen dar\u00fcber auf, ob die Bereitstellung der personenbezogenen Daten gesetzlich oder vertraglich vorgeschrieben oder f\u00fcr den Vertragsabschluss erforderlich ist, ob eine Verpflichtung besteht, die personenbezogenen Daten bereitzustellen, und welche Folgen die Nichtbereitstellung der personenbezogenen Daten h\u00e4tte.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">10. Bestehen einer automatisierten Entscheidungsfindung<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Als verantwortungsbewusstes Unternehmen verzichten wir auf eine automatische Entscheidungsfindung oder ein Profiling.<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">\u00a0<\/span><\/p><p><span lang=\"DE\" style=\"mso-ansi-language: DE;\">Diese Datenschutzerkl\u00e4rung wurde durch den Datenschutzerkl\u00e4rungs-Generator der DGD Deutsche Gesellschaft f\u00fcr Datenschutz GmbH, die als Externer Datenschutzbeauftragter Oberbayern t\u00e4tig ist, in Kooperation mit den Datenschutz Anw\u00e4lten der Kanzlei WILDE BEUGER SOLMECKE | Rechtsanw\u00e4lte erstellt.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Wir freuen uns sehr \u00fcber Ihr Interesse an unserem Unternehmen. Datenschutz hat einen besonders hohen Stellenwert f\u00fcr die Gesch\u00e4ftsleitung der Digital Patent Solutions UG (haftungsbeschr\u00e4nkt). Eine Nutzung der Internetseiten der Digital Patent Solutions UG (haftungsbeschr\u00e4nkt) ist grunds\u00e4tzlich ohne jede Angabe personenbezogener Daten m\u00f6glich. Sofern eine betroffene Person besondere Services unseres Unternehmens \u00fcber unsere [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/patent-viewer.eu\/index.php\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/patent-viewer.eu\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/patent-viewer.eu\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/patent-viewer.eu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/patent-viewer.eu\/index.php\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":31,"href":"https:\/\/patent-viewer.eu\/index.php\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":1971,"href":"https:\/\/patent-viewer.eu\/index.php\/wp-json\/wp\/v2\/pages\/3\/revisions\/1971"}],"wp:attachment":[{"href":"https:\/\/patent-viewer.eu\/index.php\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}